{"id":64015,"date":"2023-04-17T12:35:03","date_gmt":"2023-04-17T12:35:03","guid":{"rendered":"https:\/\/www.supermemo.com\/?p=64015"},"modified":"2023-05-29T12:28:18","modified_gmt":"2023-05-29T12:28:18","slug":"ai-en-supermemo","status":"publish","type":"post","link":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo","title":{"rendered":"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs"},"content":{"rendered":"<div class=\"container\"><div class=\"row\"><div class=\"col-md-10 col-lg-9 col-xl-8 mx-auto\"><div class=\"entry-content\">\n<p class=\"wp-block-paragraph\">Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, <a href=\"https:\/\/www.supermemo.com\/wp-content\/uploads\/SuperMemo_AI.pdf\">El Modelo de repetici\u00f3n espaciada con LSTMs<\/a>, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. Explora el potencial de las redes neuronales Long Short-Term Memory (LSTM) en el \u00e1mbito de la repetici\u00f3n espaciada.<\/p>\n\n<p class=\"wp-block-paragraph\">En SuperMemo, comenzamos la investigaci\u00f3n en la optimizaci\u00f3n de la repetici\u00f3n asistida por computadora (<a href=\"https:\/\/www.supermemo.com\/en\/supermemo-method\">spaced repetition<\/a>) y publicamos la primera aplicaci\u00f3n inform\u00e1tica del mundo que utiliza este m\u00e9todo. Hasta el d\u00eda de hoy, cuenta con m\u00e1s de<a href=\"https:\/\/www.supermemo.com\/en\/blog\/the-true-history-of-spaced-repetition\"> 30 a\u00f1os de historia<\/a> y desarrollo. Nos enorgullece no solo haber iniciado la tendencia que ahora siguen todas las principales aplicaciones educativas, sino tambi\u00e9n presentar otro hito en el desarrollo de este m\u00e9todo. Se trata del uso del aprendizaje autom\u00e1tico para predecir de manera efectiva la retenci\u00f3n de la memoria y proporcionar una gu\u00eda de aprendizaje \u00f3ptima.<\/p>\n\n<h2 class=\"wp-block-heading\">Sobre nuestra investigaci\u00f3n: AI en SuperMemo<\/h2>\n\n<p class=\"wp-block-paragraph\">En la investigaci\u00f3n, realizamos una revisi\u00f3n exhaustiva de trabajos anteriores sobre el tema, probando y comparando diferentes m\u00e9todos para seleccionar el m\u00e1s efectivo. Al aprovechar nuestros conocimientos expertos en repetici\u00f3n espaciada trabajados a lo largo de los a\u00f1os, as\u00ed como los datos de aprendizaje masivo recopilados en el ecosistema <a href=\"http:\/\/www.supermemo.com\/\">www.SuperMemo.com<\/a>, pudimos acelerar el proceso de aprendizaje de nuestro modelo LSTM, haci\u00e9ndolo a\u00fan m\u00e1s efectivo. En cierto sentido, el algoritmo SuperMemo basado en aprendizaje autom\u00e1tico es similar al algoritmo experto, pero utiliza diferentes m\u00e9todos de optimizaci\u00f3n para alcanzar los mismos objetivos<\/p>\n\n<p class=\"wp-block-paragraph\">Nuestro modelo LSTM est\u00e1 dise\u00f1ado para predecir la probabilidad de recordar elementos particulares por parte de un usuario y planificar intervalos \u00f3ptimos de revisi\u00f3n, minimizando en \u00faltima instancia el tiempo dedicado a las revisiones y manteniendo un alto nivel de retenci\u00f3n de conocimientos. Comparamos el modelo construido de esta manera con otros enfoques de aprendizaje autom\u00e1tico, como la regresi\u00f3n log\u00edstica, las redes neuronales feedforward o la regresi\u00f3n de semivida, y encontramos que nuestro modelo LSTM super\u00f3 consistentemente a los dem\u00e1s. Esto demuestra el valor de las redes neuronales LSTM en el campo de la repetici\u00f3n espaciada y su capacidad para mejorar la efectividad de SuperMemo.<\/p>\n\n<p class=\"wp-block-paragraph\">Al incorporar la teor\u00eda de la memoria a largo plazo en los modelos LSTM, podemos proporcionar una alternativa efectiva basada en ML a los m\u00e9todos expertos hasta ahora imbatibles. Adem\u00e1s, el algoritmo SuperMemo basado en aprendizaje autom\u00e1tico est\u00e1 abierto a un mayor desarrollo, incluida la integraci\u00f3n de m\u00faltiples nuevos par\u00e1metros. Por ejemplo, podemos incorporar aspectos como la hora del d\u00eda, el ciclo de sue\u00f1o, el nivel de estr\u00e9s o fatiga, las dependencias de contenido o las correlaciones ling\u00fc\u00edsticas en el c\u00e1lculo. Podemos investigar la influencia de estos par\u00e1metros en el aprendizaje, refinando y personalizando continuamente nuestros m\u00e9todos.<\/p>\n\n<h2 class=\"wp-block-heading\">Conferencia en Praga <\/h2>\n\n<p class=\"wp-block-paragraph\">Estamos emocionados de presentar este art\u00edculo en <a href=\"https:\/\/csedu.scitevents.org\/\">CSEDU<\/a>, International Conference on Computer Supported Education, en Praga el 21 de abril de 2023. A medida que continuamos revolucionando el aprendizaje y el desarrollo personal, creemos que estos hallazgos contribuir\u00e1n significativamente a la continua refinaci\u00f3n y mejora de SuperMemo.<\/p>\n\n<p class=\"wp-block-paragraph\">Nuestro viaje en perfeccionar algoritmos de repetici\u00f3n espaciada siempre ha sido sobre proporcionar la mejor experiencia de aprendizaje posible para usted. Con esta nueva investigaci\u00f3n, nuestro objetivo es continuar nuestra tradici\u00f3n de innovaci\u00f3n y excelencia, haciendo que SuperMemo sea a\u00fan m\u00e1s efectivo y adaptable a sus necesidades de aprendizaje.<\/p>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. Explora el potencial de las redes neuronales Long Short-Term Memory (LSTM) en el \u00e1mbito de la repetici\u00f3n espaciada.","protected":false},"author":14,"featured_media":63840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1840,1842],"tags":[1751,1750,1749,1748],"class_list":["post-64015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aprendizaje-con-supermemo","category-novedades","tag-investigacion-cientifica","tag-news-2","tag-spaced-repetition-3","tag-supermemo-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs<\/title>\n<meta name=\"description\" content=\"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. AI en SuperMemo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs\" \/>\n<meta property=\"og:description\" content=\"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. AI en SuperMemo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo\" \/>\n<meta property=\"og:site_name\" content=\"SuperMemo\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T12:35:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-29T12:28:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.supermemo.com\/wp-content\/uploads\/photo-Christin-Hume.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paulina Szedler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paulina Szedler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo\"},\"author\":{\"name\":\"Paulina Szedler\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#\\\/schema\\\/person\\\/68d13ede0b6bb36a23cb1c2499d126d6\"},\"headline\":\"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs\",\"datePublished\":\"2023-04-17T12:35:03+00:00\",\"dateModified\":\"2023-05-29T12:28:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo\"},\"wordCount\":624,\"publisher\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.supermemo.com\\\/wp-content\\\/uploads\\\/photo-Christin-Hume.jpg\",\"keywords\":[\"investigaci\u00f3n cient\u00edfica\",\"news\",\"spaced repetition\",\"supermemo\"],\"articleSection\":[\"Aprendizaje con SuperMemo\",\"Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo\",\"url\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo\",\"name\":\"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.supermemo.com\\\/wp-content\\\/uploads\\\/photo-Christin-Hume.jpg\",\"datePublished\":\"2023-04-17T12:35:03+00:00\",\"dateModified\":\"2023-05-29T12:28:18+00:00\",\"description\":\"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. AI en SuperMemo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#primaryimage\",\"url\":\"https:\\\/\\\/www.supermemo.com\\\/wp-content\\\/uploads\\\/photo-Christin-Hume.jpg\",\"contentUrl\":\"https:\\\/\\\/www.supermemo.com\\\/wp-content\\\/uploads\\\/photo-Christin-Hume.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Woman with a laptop\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/ai-en-supermemo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SuperMemo\",\"item\":\"https:\\\/\\\/www.supermemo.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprendizaje con SuperMemo\",\"item\":\"https:\\\/\\\/www.supermemo.com\\\/es\\\/blog\\\/category\\\/aprendizaje-con-supermemo\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#website\",\"url\":\"https:\\\/\\\/www.supermemo.com\\\/es\",\"name\":\"SuperMemo\",\"description\":\"SuperMemo\u00ae - skuteczna nauka j\u0119zyk\u00f3w online.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.supermemo.com\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#organization\",\"name\":\"SuperMemo World\",\"url\":\"https:\\\/\\\/www.supermemo.com\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.supermemo.com\\\/wp-content\\\/uploads\\\/supermemo_logo696x696.png\",\"contentUrl\":\"https:\\\/\\\/www.supermemo.com\\\/wp-content\\\/uploads\\\/supermemo_logo696x696.png\",\"width\":696,\"height\":696,\"caption\":\"SuperMemo World\"},\"image\":{\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.supermemo.com\\\/es#\\\/schema\\\/person\\\/68d13ede0b6bb36a23cb1c2499d126d6\",\"name\":\"Paulina Szedler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf9dc8746a3021b4f98a0c432e9a1d7083714fb34a76e971338c152d92dc58c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf9dc8746a3021b4f98a0c432e9a1d7083714fb34a76e971338c152d92dc58c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf9dc8746a3021b4f98a0c432e9a1d7083714fb34a76e971338c152d92dc58c4?s=96&d=mm&r=g\",\"caption\":\"Paulina Szedler\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs","description":"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. AI en SuperMemo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo","og_locale":"es_ES","og_type":"article","og_title":"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs","og_description":"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. AI en SuperMemo","og_url":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo","og_site_name":"SuperMemo","article_published_time":"2023-04-17T12:35:03+00:00","article_modified_time":"2023-05-29T12:28:18+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.supermemo.com\/wp-content\/uploads\/photo-Christin-Hume.jpg","type":"image\/jpeg"}],"author":"Paulina Szedler","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Paulina Szedler","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#article","isPartOf":{"@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo"},"author":{"name":"Paulina Szedler","@id":"https:\/\/www.supermemo.com\/es#\/schema\/person\/68d13ede0b6bb36a23cb1c2499d126d6"},"headline":"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs","datePublished":"2023-04-17T12:35:03+00:00","dateModified":"2023-05-29T12:28:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo"},"wordCount":624,"publisher":{"@id":"https:\/\/www.supermemo.com\/es#organization"},"image":{"@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#primaryimage"},"thumbnailUrl":"https:\/\/www.supermemo.com\/wp-content\/uploads\/photo-Christin-Hume.jpg","keywords":["investigaci\u00f3n cient\u00edfica","news","spaced repetition","supermemo"],"articleSection":["Aprendizaje con SuperMemo","Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo","url":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo","name":"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs","isPartOf":{"@id":"https:\/\/www.supermemo.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#primaryimage"},"image":{"@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#primaryimage"},"thumbnailUrl":"https:\/\/www.supermemo.com\/wp-content\/uploads\/photo-Christin-Hume.jpg","datePublished":"2023-04-17T12:35:03+00:00","dateModified":"2023-05-29T12:28:18+00:00","description":"Nos complace anunciar nuestro \u00faltimo avance en investigaci\u00f3n, El Modelo de repetici\u00f3n espaciada con LSTMs, creado en colaboraci\u00f3n entre el equipo de SuperMemo y cient\u00edficos de la Facultad de Matem\u00e1ticas e Inform\u00e1tica de la Universidad Adam Mickiewicz en Pozna\u0144. AI en SuperMemo","breadcrumb":{"@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#primaryimage","url":"https:\/\/www.supermemo.com\/wp-content\/uploads\/photo-Christin-Hume.jpg","contentUrl":"https:\/\/www.supermemo.com\/wp-content\/uploads\/photo-Christin-Hume.jpg","width":1080,"height":1080,"caption":"Woman with a laptop"},{"@type":"BreadcrumbList","@id":"https:\/\/www.supermemo.com\/es\/blog\/ai-en-supermemo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SuperMemo","item":"https:\/\/www.supermemo.com\/es"},{"@type":"ListItem","position":2,"name":"Aprendizaje con SuperMemo","item":"https:\/\/www.supermemo.com\/es\/blog\/category\/aprendizaje-con-supermemo"},{"@type":"ListItem","position":3,"name":"AI en SuperMemo: Pioneros en la repetici\u00f3n espaciada con LSTMs"}]},{"@type":"WebSite","@id":"https:\/\/www.supermemo.com\/es#website","url":"https:\/\/www.supermemo.com\/es","name":"SuperMemo","description":"SuperMemo\u00ae - skuteczna nauka j\u0119zyk\u00f3w online.","publisher":{"@id":"https:\/\/www.supermemo.com\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.supermemo.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.supermemo.com\/es#organization","name":"SuperMemo World","url":"https:\/\/www.supermemo.com\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.supermemo.com\/es#\/schema\/logo\/image\/","url":"https:\/\/www.supermemo.com\/wp-content\/uploads\/supermemo_logo696x696.png","contentUrl":"https:\/\/www.supermemo.com\/wp-content\/uploads\/supermemo_logo696x696.png","width":696,"height":696,"caption":"SuperMemo World"},"image":{"@id":"https:\/\/www.supermemo.com\/es#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.supermemo.com\/es#\/schema\/person\/68d13ede0b6bb36a23cb1c2499d126d6","name":"Paulina Szedler","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cf9dc8746a3021b4f98a0c432e9a1d7083714fb34a76e971338c152d92dc58c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf9dc8746a3021b4f98a0c432e9a1d7083714fb34a76e971338c152d92dc58c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf9dc8746a3021b4f98a0c432e9a1d7083714fb34a76e971338c152d92dc58c4?s=96&d=mm&r=g","caption":"Paulina Szedler"}}]}},"_links":{"self":[{"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/posts\/64015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/comments?post=64015"}],"version-history":[{"count":0,"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/posts\/64015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/media\/63840"}],"wp:attachment":[{"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/media?parent=64015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/categories?post=64015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.supermemo.com\/es\/wp-json\/wp\/v2\/tags?post=64015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}